{"id":335,"date":"2020-03-24T15:58:09","date_gmt":"2020-03-24T14:58:09","guid":{"rendered":"http:\/\/armeedusalut.be\/liege\/?p=335"},"modified":"2020-03-24T15:58:09","modified_gmt":"2020-03-24T14:58:09","slug":"trouvez-le-centre-le-plus-proche-de-chez-vous","status":"publish","type":"post","link":"https:\/\/armeedusalut.be\/liege\/trouvez-le-centre-le-plus-proche-de-chez-vous\/","title":{"rendered":"Trouvez le centre le plus proche de chez vous"},"content":{"rendered":"<p>Pendant les moments difficiles que nous connaissons,\u00a0 L\u2019Arm\u00e9e du Salut avec la Ville de Li\u00e8ge assurent la livraison des denr\u00e9es sur 3 points de rendez-vous et la livraison \u00e0 domicile pour les personnes \u00e2g\u00e9es.<\/p>\n<ul>\n<li>La Maison interg\u00e9n\u00e9rationnelle d\u2019Outremeuse situ\u00e9e Rue Raes de Heers, 13.<\/li>\n<li>La Maison interg\u00e9n\u00e9rationnelle de Sainte-Walburge situ\u00e9e Boulevard des Hauteurs, 39B.<\/li>\n<li>Les Services sociaux de Proximit\u00e9, Avenue Albert 1er, 5.<\/li>\n<\/ul>\n<p>Des agents communaux seront affect\u00e9s \u00e0 cette distribution et les b\u00e9n\u00e9ficiaires seront re\u00e7us sur rendez-vous afin d\u2019organiser l\u2019indispensable distanciation sociale.<\/p>\n<p>Les b\u00e9n\u00e9ficiaires de l\u2019aide alimentaire pourront prendre rendez-vous aux num\u00e9ros 04\/221.84.32 ou 04\/221.84.57 (de 9h30 \u00e0 16h30, du lundi au samedi) pour recevoir leur colis dans un des trois lieux publics cit\u00e9s plus haut.<\/p>\n<p>La distribution des colis alimentaires dans les trois lieux pr\u00e9cit\u00e9s d\u00e9butera le mardi 24 mars 2020.<\/p>\n<p>La Ville de Li\u00e8ge souhaite \u00e9galement faire un appel aux restaurateurs qui disposent de denr\u00e9es p\u00e9rissables dont ils ne vont pas pouvoir se servir. Ils peuvent en faire don pour la confection des colis alimentaires au 04\/221.84.32.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pendant les moments difficiles que nous connaissons,\u00a0 L\u2019Arm\u00e9e du Salut avec la Ville de Li\u00e8ge assurent la livraison des denr\u00e9es sur 3 points de rendez-vous et la livraison \u00e0 domicile pour les personnes \u00e2g\u00e9es. La Maison interg\u00e9n\u00e9rationnelle d\u2019Outremeuse situ\u00e9e Rue Raes de Heers, 13. La Maison interg\u00e9n\u00e9rationnelle de Sainte-Walburge situ\u00e9e Boulevard des Hauteurs, 39B. Les&hellip;<\/p>\n","protected":false},"author":5,"featured_media":336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wds_primary_category":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","entry","has-media"],"_links":{"self":[{"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/posts\/335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/comments?post=335"}],"version-history":[{"count":0,"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/posts\/335\/revisions"}],"wp:attachment":[{"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/media?parent=335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/categories?post=335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/armeedusalut.be\/liege\/wp-json\/wp\/v2\/tags?post=335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}